{"id":3471,"date":"2023-07-24T11:43:04","date_gmt":"2023-07-24T11:43:04","guid":{"rendered":"https:\/\/goodlivingthailand.com\/?post_type=product&#038;p=3471"},"modified":"2026-06-03T09:59:22","modified_gmt":"2026-06-03T09:59:22","slug":"bialetti-moka-express-italy-6-cups","status":"publish","type":"product","link":"https:\/\/goodlivingthailand.com\/index.php\/product\/bialetti-moka-express-italy-6-cups\/","title":{"rendered":"Bialetti \u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f Moka Pot \u0e23\u0e38\u0e48\u0e19 Moka Express (\u0e42\u0e21\u0e04\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a) \u0e02\u0e19\u0e32\u0e14 6 \u0e16\u0e49\u0e27\u0e22 &#8211; Tricolor Italy [BL-0005323]"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<article class=\"4ever-article\" data-clipboard-cangjie=\"[&quot;root&quot;,{&quot;copyFrom&quot;:1872268905},[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2b50&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e48\u0e07&quot;],[&quot;span&quot;,{&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2b50 &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u2013 \u0e28\u0e38\u0e01\u0e23\u0e4c&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49\u0e08\u0e32\u0e01 &quot;],[&quot;span&quot;,{&quot;bold&quot;:true,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;Bialetti Official Store&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e07\u0e2a\u0e31\u0e22 \u0e14\u0e49\u0e27\u0e22\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f Bialetti \u0e23\u0e38\u0e48\u0e19 Moka Express (\u0e42\u0e21\u0e04\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a) \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35 \u0e04.\u0e28.1933 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e14\u0e49\u0e27\u0e22\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e41\u0e1b\u0e14\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19 \u0e04\u0e25\u0e49\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e07\u0e01\u0e32\u0e41\u0e1f\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e39\u0e07&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49 Bialetti \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e21\u0e32&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;Bialetti Moka Pot \u0e23\u0e38\u0e48\u0e19 Moka Express (\u0e42\u0e21\u0e04\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a) \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e38\u0e48\u0e19\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c Bialetti \u0e08\u0e36\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e40\u0e2d\u0e2a\u0e40\u0e1e\u0e23\u0e2a\u0e42\u0e0b\u0e48\u0e44\u0e14\u0e49\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e41\u0e17\u0e49 \u0e46 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e41\u0e1f\u0e40\u0e2d\u0e2a\u0e40\u0e1e\u0e23\u0e2a\u0e42\u0e0b\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e21\u0e19\u0e39\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 &quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;Bialetti Moka Express \u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32 \u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e14\u0e49\u0e32\u0e21\u0e08\u0e31\u0e1a\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a Inspection valve \u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07 Bialetti \u0e44\u0e14\u0e49\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e14\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e19\u0e34\u0e21&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2022&quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e23\u0e38\u0e48\u0e19 : Moka Express&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2022&quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e02\u0e19\u0e32\u0e14 : 6 Cup \u0e2b\u0e23\u0e37\u0e2d 270 ml.&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2022&quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e2a\u0e35 : Tricolor Italy (\u0e2a\u0e35\u0e18\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35)&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2022&quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e1c\u0e25\u0e34\u0e15 : \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 (Made in Italy)&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2022&quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e27\u0e31\u0e2a\u0e14\u0e38 : \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 (Food Grade)&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2022&quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e15\u0e32 : \u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a \u0e40\u0e15\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01 (\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e15\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e44\u0e14\u0e49)&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2022&quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; &quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e02\u0e19\u0e32\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 : \u0e01\u0e27\u0e49\u0e32\u0e07 11.3 \u0e0b\u0e21. \u0e22\u0e32\u0e27 16.3 \u0e0b\u0e21. \u0e2a\u0e39\u0e07 22 \u0e0b\u0e21.&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2665&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f Bialetti \u0e17\u0e38\u0e01\u0e0a\u0e34\u0e49\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e41\u0e1a\u0e1a &quot;],[&quot;span&quot;,{&quot;bold&quot;:true,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;Semi-handcraft&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; \u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e02\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e42\u0e21\u0e04\u0e32\u0e1e\u0e2d\u0e15 (Moka Pot)&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2665&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; \u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48&quot;],[&quot;span&quot;,{&quot;bold&quot;:true,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;1. \u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e15\u0e31\u0e27\u0e2b\u0e21\u0e49\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19, \u0e01\u0e23\u0e27\u0e22\u0e01\u0e23\u0e2d\u0e07, \u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e48\u0e32\u0e07&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;2. \u0e23\u0e2d\u0e22\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e42\u0e21\u0e04\u0e32\u0e1e\u0e2d\u0e15 (Moka Pot) \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35 \u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e01\u0e27\u0e48\u0e32 1 \u0e19\u0e34\u0e49\u0e27&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;3. \u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e23\u0e2d\u0e22\u0e15\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2665&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; \u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48&quot;],[&quot;span&quot;,{&quot;bold&quot;:true,&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e44\u0e21\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;1. \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e35\u0e16\u0e25\u0e2d\u0e01 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e01\u0e34\u0e19\u0e01\u0e27\u0e48\u0e32 1 \u0e19\u0e34\u0e49\u0e27&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;2. \u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e23\u0e31\u0e48\u0e27\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e44\u0e14\u0e49&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;3. \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e20\u0e32\u0e1e\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e32\u0e14\u0e2b\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e21\u0e48\u0e04\u0e23\u0e1a \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e23\u0e27\u0e22\u0e01\u0e23\u0e2d\u0e07, \u0e0b\u0e35\u0e25\u0e22\u0e32\u0e07, \u0e2b\u0e39\u0e08\u0e31\u0e1a, \u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49\u0e27\u0e32\u0e25\u0e4c\u0e27,\u0e27\u0e32\u0e25\u0e4c\u0e27\u0e15\u0e35\u0e1f\u0e2d\u0e07\u0e19\u0e21 \u0e2f\u0e25\u0e2f&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2665&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;1. \u0e40\u0e15\u0e34\u0e21\u0e19\u0e49\u0e33\u0e25\u0e07\u0e43\u0e19\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e15\u0e49\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e27\u0e32\u0e25\u0e4c\u0e27&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;2. \u0e15\u0e31\u0e01\u0e01\u0e32\u0e41\u0e1f\u0e43\u0e2a\u0e48\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e01\u0e23\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19 (\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27\u0e1a\u0e14\u0e2b\u0e22\u0e32\u0e1a\u0e02\u0e19\u0e32\u0e14\u0e40\u0e17\u0e48\u0e32\u0e40\u0e01\u0e25\u0e47\u0e14\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e22\u0e32\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a 4)&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;3. \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19-\u0e25\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;4. \u0e15\u0e31\u0e49\u0e07\u0e40\u0e15\u0e32\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e15\u0e49\u0e21\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 4-7 \u0e19\u0e32\u0e17\u0e35&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;5. \u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e27\u0e48\u0e32\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e08\u0e30\u0e14\u0e31\u0e19\u0e19\u0e49\u0e33\u0e01\u0e32\u0e41\u0e1f\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19 \u0e2b\u0e32\u0e01\u0e19\u0e49\u0e33\u0e01\u0e32\u0e41\u0e1f\u0e14\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2665&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; \u0e02\u0e49\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;1. \u0e42\u0e1b\u0e23\u0e14\u0e23\u0e30\u0e27\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;2. \u0e40\u0e01\u0e47\u0e1a\u0e25\u0e49\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e43\u0e14 \u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e15\u0e32\u0e01\u0e44\u0e27\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e2b\u0e49\u0e07\u0e2a\u0e19\u0e34\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e47\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e2b\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;3. \u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e43\u0e0a\u0e49\u0e1d\u0e2d\u0e22\u0e02\u0e31\u0e14\u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e21\u0e43\u0e14 \u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;color&quot;:&quot;rgb(77, 81, 86)&quot;,&quot;sz&quot;:10.5,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u2665&quot;],[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot; \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e35\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{&quot;firstLine&quot;:32},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:11,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;\u0e01\u0e23\u0e13\u0e35\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e35\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e30\u0e1a\u0e38\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e08\u0e49\u0e07\u0e17\u0e32\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d \u0e42\u0e14\u0e22\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e08\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32&quot;]]],[&quot;p&quot;,{&quot;jc&quot;:&quot;left&quot;,&quot;ind&quot;:{},&quot;spacing&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]],[&quot;img&quot;,{&quot;src&quot;:&quot;https:\/\/th-live-01.slatic.net\/p\/d92746d782e50ceaf9223af8eec00cf0.png&quot;,&quot;style&quot;:&quot;width: 881.0px;height: 1228.1088px;display: inline;vertical-align: middle;&quot;,&quot;width&quot;:881,&quot;height&quot;:1228},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]],[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;&quot;]]]]\">\u2b50\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e48\u0e07\u2b50\u00a0\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u00a0\u2013\u00a0\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49\u0e08\u0e32\u0e01 Goodliving Official Store\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e07\u0e2a\u0e31\u0e22\u00a0\u0e14\u0e49\u0e27\u0e22\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u00a0Bialetti\u00a0\u0e23\u0e38\u0e48\u0e19\u00a0Moka\u00a0Express\u00a0(\u0e42\u0e21\u0e04\u0e32\u00a0\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a)\u00a0\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35<\/p>\n<p>\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35\u00a0\u0e04.\u0e28.1933\u00a0\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19<\/p>\n<p>\u0e14\u0e49\u0e27\u0e22\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e41\u0e1b\u0e14\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u00a0\u0e04\u0e25\u0e49\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e07\u0e01\u0e32\u0e41\u0e1f\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e39\u0e07<\/p>\n<p>\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u00a0Bialetti\u00a0\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e21\u0e32<\/p>\n<p>&nbsp;<\/p>\n<p>Bialetti\u00a0Moka\u00a0Pot\u00a0\u0e23\u0e38\u0e48\u0e19\u00a0Moka\u00a0Express\u00a0(\u0e42\u0e21\u0e04\u0e32\u00a0\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a)\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e38\u0e48\u0e19\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u00a0Bialetti\u00a0\u0e08\u0e36\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e40\u0e2d\u0e2a\u0e40\u0e1e\u0e23\u0e2a\u0e42\u0e0b\u0e48\u0e44\u0e14\u0e49\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e41\u0e17\u0e49\u00a0\u0e46\u00a0\u0e42\u0e14\u0e22\u0e01\u0e32\u0e41\u0e1f\u0e40\u0e2d\u0e2a\u0e40\u0e1e\u0e23\u0e2a\u0e42\u0e0b\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e21\u0e19\u0e39\u0e2d\u0e37\u0e48\u0e19\u00a0\u0e46\u00a0\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22<\/p>\n<p>Bialetti\u00a0Moka\u00a0Express\u00a0\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u00a0\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u00a0\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u00a0\u0e14\u0e49\u0e32\u0e21\u0e08\u0e31\u0e1a\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u00a0\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u00a0Inspection\u00a0valve\u00a0\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u00a0Bialetti\u00a0\u0e44\u0e14\u0e49\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e14\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u00a0\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e19\u0e34\u0e21<\/p>\n<p>\u2022\u00a0\u0e23\u0e38\u0e48\u0e19\u00a0:\u00a0Moka\u00a0Express<\/p>\n<p>\u2022\u00a0\u0e02\u0e19\u0e32\u0e14\u00a0:\u00a06\u00a0Cup\u00a0\u0e2b\u0e23\u0e37\u0e2d\u00a0270\u00a0ml.<\/p>\n<p>\u2022\u00a0\u0e2a\u0e35\u00a0:\u00a0Tricolor\u00a0Italy\u00a0(\u0e2a\u0e35\u0e18\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35)<\/p>\n<p>\u2022\u00a0\u0e1c\u0e25\u0e34\u0e15\u00a0:\u00a0\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u00a0(Made\u00a0in\u00a0Italy)<\/p>\n<p>\u2022\u00a0\u0e27\u0e31\u0e2a\u0e14\u0e38\u00a0:\u00a0\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u00a0(Food\u00a0Grade)<\/p>\n<p>\u2022\u00a0\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e15\u0e32\u00a0:\u00a0\u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a\u00a0\u0e40\u0e15\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32\u00a0\u0e40\u0e15\u0e32\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01\u00a0(\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e15\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e44\u0e14\u0e49)<\/p>\n<p>\u2022\u00a0\u0e02\u0e19\u0e32\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u00a0:\u00a0\u0e01\u0e27\u0e49\u0e32\u0e07\u00a011.3\u00a0\u0e0b\u0e21.\u00a0\u0e22\u0e32\u0e27\u00a016.3\u00a0\u0e0b\u0e21.\u00a0\u0e2a\u0e39\u0e07\u00a022\u00a0\u0e0b\u0e21.<\/p>\n<p>&nbsp;<\/p>\n<p>\u2665\u00a0\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u00a0Bialetti\u00a0\u0e17\u0e38\u0e01\u0e0a\u0e34\u0e49\u0e19\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u00a0Semi-handcraft\u00a0\u00a0\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u00a0\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e02\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d\u00a0\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e14\u0e49\u00a0\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e42\u0e21\u0e04\u0e32\u0e1e\u0e2d\u0e15\u00a0(Moka\u00a0Pot)<\/p>\n<p>&nbsp;<\/p>\n<p>\u2665\u00a0\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19<\/p>\n<p>1.\u00a0\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e15\u0e31\u0e27\u0e2b\u0e21\u0e49\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19,\u00a0\u0e01\u0e23\u0e27\u0e22\u0e01\u0e23\u0e2d\u0e07,\u00a0\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e48\u0e32\u0e07<\/p>\n<p>2.\u00a0\u0e23\u0e2d\u0e22\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e01\u0e32\u0e41\u0e1f\u00a0\u0e42\u0e21\u0e04\u0e32\u0e1e\u0e2d\u0e15\u00a0(Moka\u00a0Pot)\u00a0\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u00a0\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e01\u0e27\u0e48\u0e32\u00a01\u00a0\u0e19\u0e34\u0e49\u0e27<\/p>\n<p>3.\u00a0\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e23\u0e2d\u0e22\u0e15\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/p>\n<p>&nbsp;<\/p>\n<p>\u2665\u00a0\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19<\/p>\n<p>1.\u00a0\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e35\u0e16\u0e25\u0e2d\u0e01\u00a0\u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e01\u0e34\u0e19\u0e01\u0e27\u0e48\u0e32\u00a01\u00a0\u0e19\u0e34\u0e49\u0e27<\/p>\n<p>2.\u00a0\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e23\u0e31\u0e48\u0e27\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e44\u0e14\u0e49<\/p>\n<p>3.\u00a0\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e20\u0e32\u0e1e\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e32\u0e14\u0e2b\u0e32\u0e22\u00a0\u0e40\u0e0a\u0e48\u0e19\u00a0\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e21\u0e48\u0e04\u0e23\u0e1a\u00a0\u0e2d\u0e32\u0e17\u0e34\u00a0\u0e01\u0e23\u0e27\u0e22\u0e01\u0e23\u0e2d\u0e07,\u00a0\u0e0b\u0e35\u0e25\u0e22\u0e32\u0e07,\u00a0\u0e2b\u0e39\u0e08\u0e31\u0e1a,\u00a0\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49\u0e27\u0e32\u0e25\u0e4c\u0e27,\u0e27\u0e32\u0e25\u0e4c\u0e27\u0e15\u0e35\u0e1f\u0e2d\u0e07\u0e19\u0e21\u00a0\u0e2f\u0e25\u0e2f<\/p>\n<p>&nbsp;<\/p>\n<p>\u2665\u00a0\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\n<p>1.\u00a0\u0e40\u0e15\u0e34\u0e21\u0e19\u0e49\u0e33\u0e25\u0e07\u0e43\u0e19\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e15\u0e49\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e27\u0e32\u0e25\u0e4c\u0e27<\/p>\n<p>2.\u00a0\u0e15\u0e31\u0e01\u0e01\u0e32\u0e41\u0e1f\u0e43\u0e2a\u0e48\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e01\u0e23\u0e27\u0e22\u00a0\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19\u00a0(\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27\u0e1a\u0e14\u0e2b\u0e22\u0e32\u0e1a\u0e02\u0e19\u0e32\u0e14\u0e40\u0e17\u0e48\u0e32\u0e40\u0e01\u0e25\u0e47\u0e14\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e22\u0e32\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u00a04)<\/p>\n<p>3.\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19-\u0e25\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u00a0\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19<\/p>\n<p>4.\u00a0\u0e15\u0e31\u0e49\u0e07\u0e40\u0e15\u0e32\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u00a0\u0e15\u0e49\u0e21\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u00a04-7\u00a0\u0e19\u0e32\u0e17\u0e35<\/p>\n<p>5.\u00a0\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e27\u0e48\u0e32\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e08\u0e30\u0e14\u0e31\u0e19\u0e19\u0e49\u0e33\u0e01\u0e32\u0e41\u0e1f\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19\u00a0\u0e2b\u0e32\u0e01\u0e19\u0e49\u0e33\u0e01\u0e32\u0e41\u0e1f\u0e14\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e49\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e19\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e49\u0e27\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19<\/p>\n<p>&nbsp;<\/p>\n<p>\u2665\u00a0\u0e02\u0e49\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33<\/p>\n<p>1.\u00a0\u0e42\u0e1b\u0e23\u0e14\u0e23\u0e30\u0e27\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\n<p>2.\u00a0\u0e40\u0e01\u0e47\u0e1a\u0e25\u0e49\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e30\u0e2d\u0e32\u0e14\u00a0\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e43\u0e14\u00a0\u0e46\u00a0\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u00a0\u0e15\u0e32\u0e01\u0e44\u0e27\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e2b\u0e49\u0e07\u0e2a\u0e19\u0e34\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e47\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e2b\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a<\/p>\n<p>3.\u00a0\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e43\u0e0a\u0e49\u0e1d\u0e2d\u0e22\u0e02\u0e31\u0e14\u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e21\u0e43\u0e14\u00a0\u0e46\u00a0\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14<\/p>\n<p>&nbsp;<\/p>\n<p>\u2665\u00a0\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e35\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a<\/p>\n<p>\u0e01\u0e23\u0e13\u0e35\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e35\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u00a0\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e30\u0e1a\u0e38\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e08\u0e49\u0e07\u0e17\u0e32\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u00a0\u0e42\u0e14\u0e22\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e08\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/th-live-01.slatic.net\/p\/d92746d782e50ceaf9223af8eec00cf0.png\" \/><\/p>\n<\/article>\n","protected":false},"featured_media":3505,"comment_status":"open","ping_status":"closed","template":"","meta":{"iawp_total_views":141},"product_cat":[71],"product_tag":[],"class_list":["post-3471","product","type-product","status-publish","has-post-thumbnail","product_cat-moka-pot","ts_product_brand-bialetti","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/product\/3471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/comments?post=3471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/media\/3505"}],"wp:attachment":[{"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/media?parent=3471"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=3471"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/goodlivingthailand.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=3471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}